{"id":7417,"date":"2024-10-15T00:03:29","date_gmt":"2024-10-14T22:03:29","guid":{"rendered":"https:\/\/suppinger.management\/?p=7417"},"modified":"2024-11-11T12:56:05","modified_gmt":"2024-11-11T11:56:05","slug":"interim-management-restrukturierung-teil-2-von-2","status":"publish","type":"post","link":"https:\/\/suppinger.management\/en\/interim-management-restrukturierung-teil-2-von-2\/","title":{"rendered":"Interim Management &#8211; Restrukturierung Teil 2 von 2"},"content":{"rendered":"<p><strong>Wenn dann die klare Entscheidung gefallen ist, sich einer zwingend notwendigen Restrukturierung zu unterziehen, sollten gleich alle Aspekte aus Unternehmenssicht auf den Pr\u00fcfstand gestellt werden: Neben den operativen Kostensenkungsthemen m\u00fcssen auch strategische Aspekte und finanzielle Aspekte auf den Pr\u00fcfstand gestellt werden. Denn nur zeitgleich durchgef\u00fchrte Ma\u00dfnahmen wirken effizient und effektiv und garantieren damit die notwendigen Ver\u00e4nderungen im Unternehmen. Im Endeffekt wird dadurch Nachhaltigkeit gew\u00e4hrleistet. &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Daf\u00fcr gibt es in der Praxis unterschiedliche Ans\u00e4tze, die einzeln oder kombiniert f\u00fcr eine erfolgreiche Umsetzung angewendet werden k\u00f6nnen: 1. Analyse unerl\u00e4sslich f\u00fcr Performance-Check + Restrukturierungskonzept \u00dcberblick \u00fcber die wirtschaftliche und organisatorische Lage sowie die Marktpositionierung des Unternehmens 2. Unternehmens-Planung sehr wichtig f\u00fcr das Restrukturierungskonzept Beurteilung der Umsatz-, Ergebnis-, Liquidit\u00e4ts- und Eigenkapitalentwicklung 3. Ma\u00dfnahmenkatalog&nbsp; &nbsp;unerl\u00e4sslich f\u00fcr Restrukturierungskonzept Formulierung von strategischen, operativen und finanziellen Ma\u00dfnahmen, inkl. Der Verantwortlichkeiten, des Zeitrahmens und des jeweiligen Potentials 4. Umsetzung&nbsp; &nbsp;unerl\u00e4sslich f\u00fcr Umsetzungsbegleitung Projektplanung, Projektorganisation, Projektcontrolling, Start Umsetzung der Ma\u00dfnahmen &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Restrukturierung: Strategisch, operativ und finanziell<\/strong><\/p>\n\n\n\n<p><strong>In Krisensituationen muss alles schnell gehen: Management und Kapitalgeber brauchen zuverl\u00e4ssige Informationen \u00fcber den strategischen, operativen und finanziellen Zustand von Unternehmen sowie die M\u00f6glichkeiten und Grenzen von Restrukturierungskonzepten und Sanierungsma\u00dfnahmen.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>M\u00f6glichkeiten und Grenzen von Restrukturierungskonzepten und Sanierungsma\u00dfnahmen m\u00fcssen analysiert werden. Basierend auf fundierten Unternehmensinformationen, die den tats\u00e4chlichen strategischen und operativen Zustand des Unternehmens und deren Krisenursachen zum Inhalt haben, m\u00fcssen f\u00fcr und mit den Mandaten tragf\u00e4hige Konzepte und l\u00f6sungsorientierte Ma\u00dfnahmen zur Restrukturierung von sanierungsbed\u00fcrftigen Unternehmen entwickelt werden. &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Restrukturierung: Strategie und Operations Die operative Restrukturierung zielt auf die Verbesserung der Ertragslage und auf die kurzfristige Sicherung der \u00dcberlebensf\u00e4higkeit eines Krisenunternehmens. Die strategische Restrukturierung dient der Wiederherstellung der nachhaltigen Wettbewerbsf\u00e4higkeit und damit der langfristigen Sicherung der \u00dcberlebensf\u00e4higkeit. &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Zun\u00e4chst wird mit Hilfe einer operativen Restrukturierung die effektivere Aufstellung der Organisation und ihrer Prozesse untersucht. Ziel ist eine kurz- bis mittelfristig kosteng\u00fcnstigere, jedoch leistungsf\u00e4higere Aufstellung des Unternehmens. Einzubetten ist dies in den Kontext der strategischen Restrukturierung und der \u00dcberlegung, welche M\u00e4rkte oder Produkte kurz- wie langfristig Erfolg versprechen und welche Ma\u00dfnahmen daf\u00fcr umzusetzen sind &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Restrukturierung: Produktion&nbsp; &nbsp;Produktionsabl\u00e4ufe und die Supply-Chain geh\u00f6ren, wie alle anderen Unternehmenseinheiten, auf den Pr\u00fcfstand gestellt. Dabei kann Teil der strategischen Betrachtungen auch die grunds\u00e4tzliche Neuaufstellung der Produktionsbasis sein. Restrukturierung: Finanzen Refinanzierungsverhandlungen mit der engagierten Kreditwirtschaft in Zeiten von Restrukturierungsma\u00dfnahmen sind gepr\u00e4gt von Spannungen. Kreditunternehmen, die zur Bereitstellung von Fremdmitteln zur \u00dcberbr\u00fcckung von Ertrags- und Liquidit\u00e4tskrisen bereit sind, verlangen einen risikoad\u00e4quat hohen Zins. Insofern ist f\u00fcr Kreditgeber ein in sich schl\u00fcssiges Refinanzierungskonzept der Ausgangspunkt f\u00fcr eine m\u00f6gliche Vergabe von Finanzierungsmitteln. &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ziel der Restrukturierung<\/strong><\/p>\n\n\n\n<p><strong>ist zum einen die alle Bereiche \u00fcbergreifende, integrierte Unternehmensplanung und zum zweiten der Ma\u00dfnahmenplan zu allen operativen, strategischen und finanziellen Aspekten. Nur so k\u00f6nnen operative wie auch strategische Ziele neu formuliert und erreicht werden. Nur so k\u00f6nnen Krisen zu \u00fcberstanden werden. Wie gesagt: In Krisenzeiten muss alles schnell gehen.&nbsp; &nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Das setzt aber voraus, dass das Management erkennt, dass sich das Unternehmen in der Krise befindet. Daf\u00fcr gibt es Indikatoren, die dar\u00fcber Auskunft geben. Und die geh\u00f6ren stets an erste Stelle der Tagesordnung von Gesch\u00e4ftsleitungssitzungen. Dieses Thema muss kontrovers diskutiert werden. Fazit dieser Diskussion sollte die Hinzuziehung erfahrener Krisenberater sein, nur um sicher zu gehen, dass rechtzeitig die richtigen Ma\u00dfnahmen getroffen werden.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Wenn dann die klare Entscheidung gefallen ist, sich einer zwingend notwendigen Restrukturierung zu unterziehen, sollten gleich alle Aspekte aus Unternehmenssicht auf den Pr\u00fcfstand gestellt werden: Neben den operativen Kostensenkungsthemen m\u00fcssen auch strategische Aspekte und finanzielle Aspekte auf den Pr\u00fcfstand gestellt werden. Denn nur zeitgleich durchgef\u00fchrte Ma\u00dfnahmen wirken effizient und effektiv und garantieren damit die notwendigen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7455,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-7417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suppinger.management\/en\/interim-management-restrukturierung-teil-2-von-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management\" \/>\n<meta property=\"og:description\" content=\"Wenn dann die klare Entscheidung gefallen ist, sich einer zwingend notwendigen Restrukturierung zu unterziehen, sollten gleich alle Aspekte aus Unternehmenssicht auf den Pr\u00fcfstand gestellt werden: Neben den operativen Kostensenkungsthemen m\u00fcssen auch strategische Aspekte und finanzielle Aspekte auf den Pr\u00fcfstand gestellt werden. Denn nur zeitgleich durchgef\u00fchrte Ma\u00dfnahmen wirken effizient und effektiv und garantieren damit die notwendigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suppinger.management\/en\/interim-management-restrukturierung-teil-2-von-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Suppinger Interim Management\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T22:03:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T11:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jfritsch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jfritsch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/\"},\"author\":{\"name\":\"jfritsch\",\"@id\":\"https:\/\/suppinger.management\/#\/schema\/person\/540d252d6a9b37fab32452ea1fcb2b4a\"},\"headline\":\"Interim Management &#8211; Restrukturierung Teil 2 von 2\",\"datePublished\":\"2024-10-14T22:03:29+00:00\",\"dateModified\":\"2024-11-11T11:56:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/\"},\"wordCount\":599,\"publisher\":{\"@id\":\"https:\/\/suppinger.management\/#organization\"},\"image\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/\",\"url\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/\",\"name\":\"Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management\",\"isPartOf\":{\"@id\":\"https:\/\/suppinger.management\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg\",\"datePublished\":\"2024-10-14T22:03:29+00:00\",\"dateModified\":\"2024-11-11T11:56:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage\",\"url\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg\",\"contentUrl\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/suppinger.management\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interim Management &#8211; Restrukturierung Teil 2 von 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/suppinger.management\/#website\",\"url\":\"https:\/\/suppinger.management\/\",\"name\":\"Suppinger Interim Management\",\"description\":\"Struktur f&uuml;r Ihr Business\",\"publisher\":{\"@id\":\"https:\/\/suppinger.management\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/suppinger.management\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/suppinger.management\/#organization\",\"name\":\"Suppinger Interim Management\",\"url\":\"https:\/\/suppinger.management\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/suppinger.management\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2023\/08\/2023_10_31_SUPPINGER_Logo_CMYK_neu_HD-02.png\",\"contentUrl\":\"https:\/\/suppinger.management\/wp-content\/uploads\/2023\/08\/2023_10_31_SUPPINGER_Logo_CMYK_neu_HD-02.png\",\"width\":1821,\"height\":422,\"caption\":\"Suppinger Interim Management\"},\"image\":{\"@id\":\"https:\/\/suppinger.management\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/suppinger.management\/#\/schema\/person\/540d252d6a9b37fab32452ea1fcb2b4a\",\"name\":\"jfritsch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g\",\"caption\":\"jfritsch\"},\"url\":\"https:\/\/suppinger.management\/en\/author\/jfritsch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suppinger.management\/en\/interim-management-restrukturierung-teil-2-von-2\/","og_locale":"en_GB","og_type":"article","og_title":"Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management","og_description":"Wenn dann die klare Entscheidung gefallen ist, sich einer zwingend notwendigen Restrukturierung zu unterziehen, sollten gleich alle Aspekte aus Unternehmenssicht auf den Pr\u00fcfstand gestellt werden: Neben den operativen Kostensenkungsthemen m\u00fcssen auch strategische Aspekte und finanzielle Aspekte auf den Pr\u00fcfstand gestellt werden. Denn nur zeitgleich durchgef\u00fchrte Ma\u00dfnahmen wirken effizient und effektiv und garantieren damit die notwendigen [&hellip;]","og_url":"https:\/\/suppinger.management\/en\/interim-management-restrukturierung-teil-2-von-2\/","og_site_name":"Suppinger Interim Management","article_published_time":"2024-10-14T22:03:29+00:00","article_modified_time":"2024-11-11T11:56:05+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg","type":"image\/jpeg"}],"author":"jfritsch","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jfritsch","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#article","isPartOf":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/"},"author":{"name":"jfritsch","@id":"https:\/\/suppinger.management\/#\/schema\/person\/540d252d6a9b37fab32452ea1fcb2b4a"},"headline":"Interim Management &#8211; Restrukturierung Teil 2 von 2","datePublished":"2024-10-14T22:03:29+00:00","dateModified":"2024-11-11T11:56:05+00:00","mainEntityOfPage":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/"},"wordCount":599,"publisher":{"@id":"https:\/\/suppinger.management\/#organization"},"image":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage"},"thumbnailUrl":"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg","articleSection":["Uncategorized"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/","url":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/","name":"Interim Management - Restrukturierung Teil 2 von 2 | Suppinger Interim Management","isPartOf":{"@id":"https:\/\/suppinger.management\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage"},"image":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage"},"thumbnailUrl":"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg","datePublished":"2024-10-14T22:03:29+00:00","dateModified":"2024-11-11T11:56:05+00:00","breadcrumb":{"@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#primaryimage","url":"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg","contentUrl":"https:\/\/suppinger.management\/wp-content\/uploads\/2024\/10\/interim-management-restruktierung-markt.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/suppinger.management\/interim-management-restrukturierung-teil-2-von-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/suppinger.management\/"},{"@type":"ListItem","position":2,"name":"Interim Management &#8211; Restrukturierung Teil 2 von 2"}]},{"@type":"WebSite","@id":"https:\/\/suppinger.management\/#website","url":"https:\/\/suppinger.management\/","name":"Suppinger Interim Management","description":"Struktur f&uuml;r Ihr Business","publisher":{"@id":"https:\/\/suppinger.management\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suppinger.management\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/suppinger.management\/#organization","name":"Suppinger Interim Management","url":"https:\/\/suppinger.management\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/suppinger.management\/#\/schema\/logo\/image\/","url":"https:\/\/suppinger.management\/wp-content\/uploads\/2023\/08\/2023_10_31_SUPPINGER_Logo_CMYK_neu_HD-02.png","contentUrl":"https:\/\/suppinger.management\/wp-content\/uploads\/2023\/08\/2023_10_31_SUPPINGER_Logo_CMYK_neu_HD-02.png","width":1821,"height":422,"caption":"Suppinger Interim Management"},"image":{"@id":"https:\/\/suppinger.management\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/suppinger.management\/#\/schema\/person\/540d252d6a9b37fab32452ea1fcb2b4a","name":"jfritsch","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2e4ee9c7aaf563e67919b7ec5870042a609bf428d3093dd5f6722782da62ae7?s=96&d=mm&r=g","caption":"jfritsch"},"url":"https:\/\/suppinger.management\/en\/author\/jfritsch\/"}]}},"_links":{"self":[{"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/posts\/7417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/comments?post=7417"}],"version-history":[{"count":1,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/posts\/7417\/revisions"}],"predecessor-version":[{"id":7418,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/posts\/7417\/revisions\/7418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/media\/7455"}],"wp:attachment":[{"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/media?parent=7417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/categories?post=7417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/tags?post=7417"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/suppinger.management\/en\/wp-json\/wp\/v2\/post_folder?post=7417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}